{"id":8840,"date":"2019-01-03T15:21:33","date_gmt":"2019-01-03T06:21:33","guid":{"rendered":"https:\/\/vomkorea.com\/?post_type=tribe_events&#038;p=8840"},"modified":"2019-01-03T15:21:47","modified_gmt":"2019-01-03T06:21:47","slug":"%ec%95%8c%ec%a0%9c%eb%a6%ac-%eb%82%a8%ec%aa%bd-%ec%a7%80%eb%b0%a9%ec%9d%84-%eb%b9%84%eb%a1%af%ed%95%9c-%ec%95%8c%ec%a0%9c%eb%a6%ac-%eb%aa%a8%eb%93%a0-%eb%8f%84%ec%8b%9c%ec%97%90%ec%84%9c-%ec%84%b1","status":"publish","type":"tribe_events","link":"https:\/\/vomkorea.com\/zh\/event\/%ec%95%8c%ec%a0%9c%eb%a6%ac-%eb%82%a8%ec%aa%bd-%ec%a7%80%eb%b0%a9%ec%9d%84-%eb%b9%84%eb%a1%af%ed%95%9c-%ec%95%8c%ec%a0%9c%eb%a6%ac-%eb%aa%a8%eb%93%a0-%eb%8f%84%ec%8b%9c%ec%97%90%ec%84%9c-%ec%84%b1\/","title":{"rendered":"\uc54c\uc81c\ub9ac &#8211; \ub0a8\ucabd \uc9c0\ubc29\uc744 \ube44\ub86f\ud55c \uc54c\uc81c\ub9ac \ubaa8\ub4e0 \ub3c4\uc2dc\uc5d0\uc11c \uc131\uacbd\uc744 \ubc30\ud3ec\ud558\ub294 \uae30\ud68c\ub97c \uc5bb\uc744 \uc218 \uc788\ub3c4\ub85d \uae30\ub3c4\ud574\uc8fc\uc138\uc694.\u00a0 \u00a0 \u00a0"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":903,"featured_media":0,"template":"","meta":{"give_campaign_id":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[575,259],"tribe_events_cat":[254],"class_list":["post-8840","tribe_events","type-tribe_events","status-publish","hentry","tag-algeria","tag-259","tribe_events_cat-global-prayer-calendar","cat_global-prayer-calendar"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"zh","enabled_languages":["ko","en","zh","ru"],"languages":{"ko":{"title":true,"content":false,"excerpt":false},"en":{"title":true,"content":false,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/tribe_events\/8840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/users\/903"}],"version-history":[{"count":0,"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/tribe_events\/8840\/revisions"}],"wp:attachment":[{"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/media?parent=8840"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/tags?post=8840"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/vomkorea.com\/zh\/wp-json\/wp\/v2\/tribe_events_cat?post=8840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}