{"id":6920,"date":"2018-08-24T11:50:29","date_gmt":"2018-08-24T02:50:29","guid":{"rendered":"https:\/\/vomkorea.com\/?post_type=tribe_events&#038;p=6920"},"modified":"2018-08-24T11:50:29","modified_gmt":"2018-08-24T02:50:29","slug":"%eb%a7%90%eb%a0%88%ec%9d%b4%ec%8b%9c%ec%95%84-%eb%ac%b4%ec%8a%ac%eb%a6%bc%ec%9d%84-%ea%b0%9c%ec%a2%85%ec%8b%9c%ec%bc%b0%ea%b8%b0-%eb%95%8c%eb%ac%b8%ec%97%90-%ea%b0%90%ec%98%a5%ec%97%90-%ea%b0%87","status":"publish","type":"tribe_events","link":"https:\/\/vomkorea.com\/en\/event\/%eb%a7%90%eb%a0%88%ec%9d%b4%ec%8b%9c%ec%95%84-%eb%ac%b4%ec%8a%ac%eb%a6%bc%ec%9d%84-%ea%b0%9c%ec%a2%85%ec%8b%9c%ec%bc%b0%ea%b8%b0-%eb%95%8c%eb%ac%b8%ec%97%90-%ea%b0%90%ec%98%a5%ec%97%90-%ea%b0%87\/","title":{"rendered":"\ub9d0\ub808\uc774\uc2dc\uc544 &#8211; \ubb34\uc2ac\ub9bc\uc744 \uac1c\uc885\uc2dc\ucf30\uae30 \ub54c\ubb38\uc5d0 \uac10\uc625\uc5d0 \uac07\ud790 \uc218\ub3c4 \uc788\ub294 \uc804\ub3c4\uc790\ub4e4\uc758 \uc548\uc804\uc744 \uc704\ud574 \uae30\ub3c4\ud574\uc8fc\uc138\uc694."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":903,"featured_media":0,"template":"","meta":{"give_campaign_id":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[466],"tribe_events_cat":[254],"class_list":["post-6920","tribe_events","type-tribe_events","status-publish","hentry","tag-466","tribe_events_cat-global-prayer-calendar","cat_global-prayer-calendar"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["ko","en","zh","ru"],"languages":{"ko":{"title":true,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events\/6920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/users\/903"}],"version-history":[{"count":0,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events\/6920\/revisions"}],"wp:attachment":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/media?parent=6920"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tags?post=6920"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=6920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}