{"id":6465,"date":"2018-08-08T19:40:03","date_gmt":"2018-08-08T10:40:03","guid":{"rendered":"https:\/\/vomkorea.com\/?post_type=tribe_events&#038;p=6465"},"modified":"2018-08-08T19:40:03","modified_gmt":"2018-08-08T10:40:03","slug":"%ec%8b%9c%eb%a6%ac%ec%95%84-%eb%82%a9%ec%b9%98%eb%90%98%ea%b1%b0%eb%82%98-%ec%8b%a4%ec%a2%85%eb%90%9c-%ea%b8%b0%eb%8f%85%ea%b5%90%ec%9d%b8%ec%9d%98-%ea%b0%80%ec%a1%b1%eb%93%a4%ec%9d%b4-%ec%9d%b8","status":"publish","type":"tribe_events","link":"https:\/\/vomkorea.com\/en\/event\/%ec%8b%9c%eb%a6%ac%ec%95%84-%eb%82%a9%ec%b9%98%eb%90%98%ea%b1%b0%eb%82%98-%ec%8b%a4%ec%a2%85%eb%90%9c-%ea%b8%b0%eb%8f%85%ea%b5%90%ec%9d%b8%ec%9d%98-%ea%b0%80%ec%a1%b1%eb%93%a4%ec%9d%b4-%ec%9d%b8\/","title":{"rendered":"\uc2dc\ub9ac\uc544 &#8211; \ub0a9\uce58\ub418\uac70\ub098 \uc2e4\uc885\ub41c \uae30\ub3c5\uad50\uc778\uc758 \uac00\uc871\ub4e4\uc774 \uc778\ub0b4\ud558\uba70 \uc18c\ub9dd\uc744 \uc783\uc9c0 \uc54a\ub3c4\ub85d \uae30\ub3c4\ud574\uc8fc\uc138\uc694"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":903,"featured_media":0,"template":"","meta":{"give_campaign_id":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[223],"tribe_events_cat":[254],"class_list":["post-6465","tribe_events","type-tribe_events","status-publish","hentry","tag-223","tribe_events_cat-global-prayer-calendar","cat_global-prayer-calendar"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["ko","en","zh","ru"],"languages":{"ko":{"title":true,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events\/6465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/users\/903"}],"version-history":[{"count":0,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events\/6465\/revisions"}],"wp:attachment":[{"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/media?parent=6465"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tags?post=6465"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/vomkorea.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=6465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}